{"id":1901,"date":"2020-07-27T10:03:18","date_gmt":"2020-07-27T14:03:18","guid":{"rendered":"https:\/\/lowimpacthydro.org\/?page_id=1901"},"modified":"2026-06-16T11:12:48","modified_gmt":"2026-06-16T15:12:48","slug":"lihi-certificate-46-ashuelot-lower-robertson-hydroelectric-projects-new-hampshire","status":"publish","type":"page","link":"https:\/\/lowimpacthydro.org\/es\/lihi-certificate-46-ashuelot-lower-robertson-hydroelectric-projects-new-hampshire\/","title":{"rendered":"Certificado LIHI #46 \u2013 Proyectos hidroel\u00e9ctricos de Ashuelot y Lower Robertson, Nuevo Hampshire"},"content":{"rendered":"<table class=\"alignright\" style=\"width: 351px; border: 2px; cellspacing: 2px; cellpadding: 2px; margin-left: 50px;\">\n<tbody>\n<tr>\n<td style=\"width: 139px;\"><strong>Nombre del proyecto<\/strong><\/td>\n<td style=\"width: 205px;\">Papel Ashuelot y Lower Robertson<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Certificado LIHI No.<\/strong><\/td>\n<td style=\"width: 205px;\">46<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Plazo del certificado LIHI<\/strong><\/td>\n<td style=\"width: 205px;\">29 de junio de 2019 \u2013 28 de junio de 2032 (opci\u00f3n de pr\u00f3rroga hasta el 28 de junio de 2034)<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Due\u00f1o<\/strong><\/td>\n<td style=\"width: 205px;\">R\u00edo Ashuelot Hydro, Inc.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Estado<\/strong><\/td>\n<td style=\"width: 205px;\">Nuevo Hampshire<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Ubicaci\u00f3n<\/strong><\/td>\n<td style=\"width: 205px;\">Ubicado entre las millas 2 y 3 del r\u00edo Ashuelot en Winchester, New Hampshire, junto a la ruta 119 entre el pueblo de Ashuelot y la ciudad de Hinsdale.<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Capacidad instalada<\/strong><\/td>\n<td style=\"width: 205px;\"><strong>TOTAL: 1,71 MW<\/strong><\/p>\n<p>Asuelot Papde: 870 KW<br \/>\nRobertson inferior: 840 KW<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Generaci\u00f3n media anual<\/strong><\/td>\n<td style=\"width: 205px;\"><strong>TOTAL: 6.500 MW<\/strong><\/p>\n<p>Planta de papel Ashuelot: 3.300 MWh<br \/>\nBajo Robertson: 3.200 MWh<\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong>Tipo de instalaci\u00f3n<\/strong><\/td>\n<td style=\"width: 205px;\"><span class='tooltipsall tooltip_post_id_5643 classtoolTips52'>De pasada<\/span><\/td>\n<\/tr>\n<tr>\n<td style=\"width: 139px;\"><strong><span class='tooltipsall tooltip_post_id_5565 classtoolTips152'>Comisi\u00f3n Federal de Comercio<\/span> No.<\/strong><\/td>\n<td style=\"width: 205px;\">Papel Ashuelot: P-7791 exento 1986<br \/>\nLower Robertson: P-8235 exento 1986<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>Los proyectos Ashuelot Paper y Lower Robertson est\u00e1n ubicados en el r\u00edo Ashuelot en la ciudad de Winchester, en el suroeste de New Hampshire, cerca de la frontera con Hinsdale, NH. Los proyectos tienen exenciones FERC separadas (No. 7791 y No. 8235) y se construyeron en 1985 con dise\u00f1os y equipos casi id\u00e9nticos. El r\u00edo Ashuelot fluye desde su <span class='tooltipsall tooltip_post_id_5583 classtoolTips100'>cabeceras<\/span> en el parque estatal Pillsbury a trav\u00e9s de las ciudades de Gilsum y Keene para unirse al r\u00edo Connecticut en Hinsdale, New Hampshire. Las represas aguas arriba del proyecto incluyen la presa Ashuelot Park <span class='tooltipsall tooltip_post_id_5545 classtoolTips158'>Presa<\/span>, la presa de Surry Mountain, la presa de Otter Brook y la presa de Nash Mill. El molino Fiske <span class='tooltipsall tooltip_post_id_5545 classtoolTips158'>presa<\/span> Est\u00e1 situado aguas abajo.<\/p>\n<p>La presa Lower Robertson est\u00e1 ubicada aproximadamente a 1 milla r\u00edo arriba de Ashuelot Paper y tiene aproximadamente 125 pies de largo y 18 pies de alto. El proyecto tiene un control de nivel automatizado que mantiene el nivel del estanque durante los flujos normales. Hay tres conjuntos de presas Obermeyer <span class='tooltipsall tooltip_post_id_5542 classtoolTips95'>cresta <span class='tooltipsall tooltip_post_id_5578 classtoolTips153'>puertas<\/span><\/span>:dos de 16 pies de ancho por 6 pies de alto, ubicados entre los <span class='tooltipsall tooltip_post_id_5651 classtoolTips116'>aliviadero<\/span> y la estructura de entrada, y una de 76 pies de ancho por 2 pies de alto, ubicada en el aliviadero. El embalse de Lower Robertson tiene una superficie de 8,6 acres. La estructura de entrada, <span class='tooltipsall tooltip_post_id_5624 classtoolTips102'>central el\u00e9ctrica<\/span>, y el canal de descarga se encuentran en el extremo norte de la presa. La central el\u00e9ctrica tiene tres unidades de turbinas Flygt con una capacidad instalada total de 840 kW. Existe un sendero de transporte informal a lo largo de la orilla izquierda de la presa.<\/p>\n<p>La presa Ashuelot Paper tiene aproximadamente 144,5 pies de largo y 18 pies de alto. El proyecto cuenta con un control de nivel automatizado que mantiene el nivel del estanque durante los flujos normales. Hay un solo conjunto de compuertas de cresta Obermeyer a lo largo de la parte superior del aliviadero. El embalse Ashuelot Paper tiene una superficie de 1,6 acres. La estructura de entrada, la central el\u00e9ctrica y el canal de descarga se encuentran en el extremo sur de la presa. La central el\u00e9ctrica tiene tres unidades de turbina Flygt con una capacidad instalada total de 870 kW. En 2010 se construy\u00f3 un sendero de transporte que se ha mantenido desde entonces.<\/p>\n<p>Los proyectos operan en un <span class='tooltipsall tooltip_post_id_5643 classtoolTips52'>de pasada<\/span> Ambos proyectos est\u00e1n totalmente automatizados y cuentan con un sistema de control de presi\u00f3n en modo autom\u00e1tico. Los sensores de presi\u00f3n en los embalses env\u00edan datos a una computadora que garantiza que los niveles de los embalses se mantengan constantes. El proyecto prev\u00e9 un caudal m\u00ednimo de 205 pies c\u00fabicos por segundo o la entrada, lo que sea menor, desde cada proyecto para proteger el h\u00e1bitat acu\u00e1tico r\u00edo abajo. Este r\u00e9gimen de caudal se desarroll\u00f3 en base a consultas con New Hampshire Fish and Game (NHFG) y US Fish and Wildlife Service (USFWS).<\/p>\n<p>Las aguas dentro de los l\u00edmites del proyecto est\u00e1n designadas como de clase B, aunque recientemente se recopilaron datos de monitoreo de la calidad del agua por recomendaci\u00f3n del Departamento de Servicios Ambientales de New Hampshire. El NHDES brind\u00f3 recomendaciones sobre par\u00e1metros, ubicaciones y frecuencias de monitoreo y pr\u00e1cticas de control de calidad.<\/p>\n<p>El r\u00edo Ashuelot est\u00e1 actualmente en la mira <span class='tooltipsall tooltip_post_id_5518 classtoolTips36'>pez an\u00e1dromo<\/span> Restauraci\u00f3n. El proyecto de la f\u00e1brica Fiske, ubicado aguas abajo, instal\u00f3 un paso aguas arriba en 2014 para proporcionar paso a la anguila americana, el s\u00e1balo americano, la lamprea marina, el arenque azul y el salm\u00f3n del Atl\u00e1ntico. <span class='tooltipsall tooltip_post_id_5566 classtoolTips59'>paso de peces<\/span> Se construir\u00e1n en los proyectos una vez que se cumplan ciertos requisitos de paso de s\u00e1balos. Las especies de peces residentes incluyen el pez chupador blanco com\u00fan, el pez dace de hocico largo, la lubina de boca chica, el pez dardo teselado, el pez luna de agallas azules, el pez calabaza, el pez luna de pecho rojo, el pez toro amarillo, la trucha marr\u00f3n, el lucio de cadena oriental, el pez oto\u00f1al y la perca amarilla.<\/p>\n<p>En 1999 se instal\u00f3 un paso para peces r\u00edo abajo en la presa de Lower Robertson. La instalaci\u00f3n del paso consta de rejillas para basura en \u00e1ngulo, una entrada para peces debajo de las rejillas para basura, una caja de recolecci\u00f3n y un tubo de descarga en el canal de descarga. Adem\u00e1s, se instalan barras anualmente desde abril hasta el 15 de octubre en las rejillas para basura, lo que reduce el espaciado de 1-5\/8 pulgadas a 3\/4 pulgadas. En 2001 se instal\u00f3 un paso para peces r\u00edo abajo en la presa de Ashuelot Paper. De manera similar a la instalaci\u00f3n del paso en Lower Robertson, la instalaci\u00f3n del paso consta de rejillas para basura en \u00e1ngulo, una entrada para peces debajo de las rejillas para basura, una caja de recolecci\u00f3n y un tubo de descarga en el canal de descarga. Adem\u00e1s, se instalan barras anualmente desde abril hasta el 15 de octubre en las rejillas para basura, lo que reduce el espaciado de 1 y 5\/8 pulgadas a 3\/4 pulgadas.<\/p>\n<p>Las tierras del proyecto constan de aproximadamente 2,5 acres. La mayor parte de las tierras adyacentes a los embalses son de propiedad privada y est\u00e1n fuera del control del proyecto. La operaci\u00f3n de pasada minimiza el potencial de erosi\u00f3n de las costas. Los tramos aguas abajo de ambos sitios son muy similares: una corriente de r\u00e1pido movimiento en un lecho de r\u00edo relativamente empinado y rocoso, bordeado por un bosque mixto de madera dura y blanda que regresa de tierras despejadas. El desarrollo de Lower Robertson est\u00e1 ubicado junto a la Ruta 119 en el lado norte y desarrollos de molinos abandonados en el lado sur. El embalse de Ashuelot Paper est\u00e1 cubierto de bosques a ambos lados del r\u00edo. Debido a la peque\u00f1a huella del proyecto, no existen tierras de valor ecol\u00f3gico en el \u00e1rea del proyecto.<\/p>\n<p><strong>PLUS-Est\u00e1ndar:<\/strong> El propietario del proyecto realiz\u00f3 una donaci\u00f3n voluntaria a la Sociedad para la Protecci\u00f3n de los Bosques de New Hampshire para la preservaci\u00f3n de 1800 acres de tierras forestales en las cabeceras del r\u00edo Ashuelot. Las donaciones fueron: $15,000 en 2008, $5,000 en 2010 y $5,000 en 2014. La tierra se preserv\u00f3 con \u00e9xito y ahora se llama r\u00edo Ashuelot. <span class='tooltipsall tooltip_post_id_5583 classtoolTips100'>Cabeceras<\/span> Bosque. El propietario del proyecto tiene la intenci\u00f3n de seguir apoyando la preservaci\u00f3n de la cuenca del r\u00edo Ashuelot con donaciones anuales a organizaciones ambientales seleccionadas y causas que se identificaron como las que necesitan financiaci\u00f3n con mayor urgencia. Recientemente, se han hecho donaciones a proyectos en el \u00e1rea de inter\u00e9s de California Brook en Chesterfield (Monadnock Conservancy) y ahora al Surry Mountain Project en Surry (The Nature Conservancy). El propietario del proyecto tambi\u00e9n realiza donaciones a proyectos de eficiencia energ\u00e9tica en la regi\u00f3n, reconociendo que el desperdicio de energ\u00eda exacerba el cambio clim\u00e1tico.<\/p>\n<p>Las especies amenazadas o en peligro de extinci\u00f3n que podr\u00edan estar presentes en las inmediaciones del proyecto incluyen el mejill\u00f3n enano, el murci\u00e9lago orejudo norte\u00f1o y el sagitario de espinas largas. Se sabe que la especie de mejill\u00f3n habita en el r\u00edo Ashuelot, pero seg\u00fan la informaci\u00f3n del USFWS, no en las inmediaciones del proyecto. No existen sitios de hibernaci\u00f3n o descanso para murci\u00e9lagos en las \u00e1reas del proyecto, pero si se encuentran, el proyecto se ha comprometido a seguir la regla 4(d) del USFWS sobre la protecci\u00f3n del h\u00e1bitat de la especie. Los datos hist\u00f3ricos de la Oficina de Patrimonio Natural de NH indican que el sagitario de espinas largas puede estar presente en las inmediaciones del proyecto, pero el \u00faltimo avistamiento de la especie fue en 1952. En general, la zona ha logrado recuperarse de la industrializaci\u00f3n. Se han observado \u00e1guilas calvas volando sobre el proyecto, as\u00ed como garzas azules. Es muy com\u00fan avistar nutrias de r\u00edo, visones y castores.<\/p>\n<p>Si bien el proyecto Ashuelot Paper no alberga ning\u00fan recurso cultural en su \u00e1rea, la presa de Lower Robertson y sus instalaciones son de inter\u00e9s hist\u00f3rico local. Se ha consultado a la Oficina Estatal de Preservaci\u00f3n Hist\u00f3rica para determinar el impacto de las actividades de construcci\u00f3n, aunque no se han producido desde los a\u00f1os 1980. Es posible que en un futuro pr\u00f3ximo se necesiten instalaciones para el paso de peces r\u00edo arriba, aunque la SHPO ha indicado que la instalaci\u00f3n de dichas instalaciones no tendr\u00eda ning\u00fan efecto sobre los recursos hist\u00f3ricos locales. Sin embargo, el proyecto debe consultar con la SHPO para asegurarse de que no se produzcan impactos adversos en caso de que se prescriban dichas estructuras.<\/p>\n<p>Los recursos recreativos del proyecto incluyen acceso para pesca y navegaci\u00f3n, as\u00ed como un sendero para remar. El acceso p\u00fablico es gratuito.<\/p>\n<hr \/>\n<h3>Estado de cumplimiento<\/h3>\n<p><strong>El Certificado incluye las siguientes condiciones espec\u00edficas de la instalaci\u00f3n:<\/strong><\/p>\n<p><em><strong>Parcialmente satisfecho 2020<\/strong><strong>, Totalmente satisfecho en 2023<\/strong><\/em>. <strong>Condici\u00f3n 1:<\/strong> El propietario de la instalaci\u00f3n deber\u00e1 enviar copias del informe de monitoreo de calidad del agua de 2019 requerido por NHDES y toda la correspondencia con la agencia a LIHI una vez finalizado el per\u00edodo de monitoreo de 2019. LIHI se reserva el derecho de condicionar adicionalmente el Certificado LIHI del Proyecto o reconsiderar la decisi\u00f3n de certificaci\u00f3n en funci\u00f3n de la informaci\u00f3n proporcionada.<\/p>\n<p><strong><em>Opcional,<\/em> Condici\u00f3n 2: <\/strong>Si en cualquier momento antes de los seis meses previos al vencimiento del plazo de la Certificaci\u00f3n el Propietario de la Instalaci\u00f3n implementa: a) el paso de anguilas r\u00edo arriba en ambos Proyectos; y\/o extiende la temporada actual de paso de peces r\u00edo abajo en ambos Proyectos hasta el 15 de noviembre, LIHI revisar\u00e1 esa informaci\u00f3n y determinar\u00e1 si otorgar\u00e1 o no un segundo est\u00e1ndar PLUS y extender\u00e1 el plazo del Certificado por dos a\u00f1os adicionales.<\/p>\n<p><strong>2026:<\/strong> No se identificaron cambios sustanciales. LIHI y FERC recibieron cartas expresando preocupaci\u00f3n por un posible incumplimiento de las operaciones de pasada. El estado de cumplimiento del proyecto est\u00e1 pendiente seg\u00fan el resultado de las preocupaciones operativas. El proyecto inform\u00f3 que la mayor\u00eda de las preocupaciones se han mitigado. En cuanto a la Condici\u00f3n 2, el proyecto indic\u00f3 que no hubo actividad.<\/p>\n<p><strong>2025:<\/strong> No se identificaron cambios sustanciales. LIHI y FERC recibieron cartas de preocupaci\u00f3n sobre posibles incumplimientos en las operaciones de pasada. El estado de cumplimiento del proyecto est\u00e1 pendiente seg\u00fan la revisi\u00f3n anual y el resultado de las inquietudes operativas. En cuanto a la Condici\u00f3n 2, el proyecto no registr\u00f3 actividad.<\/p>\n<p><strong>2024:<\/strong> No se identificaron cambios materiales ni problemas de cumplimiento. El proyecto sigue cumpliendo con los requisitos seg\u00fan la revisi\u00f3n anual. En cuanto a la condici\u00f3n 2, el proyecto no indic\u00f3 ninguna actividad.<\/p>\n<p><strong>2023:<\/strong> No se identificaron cambios materiales ni problemas de cumplimiento. El proyecto sigue cumpliendo con los requisitos seg\u00fan la revisi\u00f3n anual. En el caso de la condici\u00f3n 1, el proyecto inform\u00f3 que a\u00fan no ha recibido respuesta de NHDES despu\u00e9s de cuatro a\u00f1os de esfuerzos reiterados por parte del proyecto para obtener una respuesta. Por lo tanto, el personal de LIHI considera que la condici\u00f3n se cumple. En el caso de la condici\u00f3n 2, el proyecto indic\u00f3 que no se ha realizado ninguna actividad.<\/p>\n<p><strong>2022:<\/strong> No se identificaron cambios materiales ni problemas de cumplimiento. El proyecto sigue cumpliendo con los requisitos seg\u00fan la revisi\u00f3n anual. En el caso de la condici\u00f3n 1, el proyecto inform\u00f3 que a\u00fan no ha recibido respuesta del NHDES. En el caso de la condici\u00f3n 2, el proyecto indic\u00f3 que no se ha realizado ninguna actividad.<\/p>\n<p><strong>2021:<\/strong> No se informaron cambios ni problemas de cumplimiento. El proyecto sigue cumpliendo con los requisitos seg\u00fan la revisi\u00f3n anual. En el caso de la condici\u00f3n 1, el proyecto inform\u00f3 que no ha recibido respuesta del NHDES. En el caso de la condici\u00f3n 2, el proyecto indic\u00f3 que no se ha realizado ninguna actividad.<\/p>\n<p><strong>2020:<\/strong> No se informaron cambios ni problemas de cumplimiento. El proyecto sigue cumpliendo con los requisitos seg\u00fan la revisi\u00f3n anual. En el caso de la condici\u00f3n 1, el proyecto confirm\u00f3 la presentaci\u00f3n al NHDES del informe de monitoreo de la calidad del agua. En el caso de la condici\u00f3n 2, el proyecto no indic\u00f3 ninguna actividad.<\/p>\n<p><strong>2019:<\/strong> La presentaci\u00f3n de informes anuales para el Certificado actual a\u00fan no ha entrado en vigor.<\/p>\n<hr \/>\n<h3>Historial de certificaciones<\/h3>\n<p><strong>1 de enero de 2022:<\/strong> El plazo del Certificado LIHI se ha extendido de acuerdo con la Revisi\u00f3n 2.05 del Manual de Certificaci\u00f3n LIHI 2.\u00aa Edici\u00f3n emitido el 1 de enero de 2022. Consulte la tabla de instalaciones anterior para conocer el nuevo plazo.<\/p>\n<p><strong>28 de octubre de 2019:<\/strong> La decisi\u00f3n de recertificar el Proyecto Hidroel\u00e9ctrico Ashuelot\/Lower Robertson es definitiva. No se recibieron apelaciones durante el per\u00edodo de apelaci\u00f3n que cerr\u00f3 el 26 de octubre de 2019. El nuevo per\u00edodo de certificaci\u00f3n del Proyecto es del 29 de junio de 2019 al 28 de junio de 2027.<\/p>\n<p><strong>26 de septiembre de 2019:\u00a0 <\/strong>El Instituto de Energ\u00eda Hidroel\u00e9ctrica de Bajo Impacto ha aprobado preliminarmente la recertificaci\u00f3n de bajo impacto para el proyecto hidroel\u00e9ctrico Ashuelot River\/Lower Robertson. Esta decisi\u00f3n es preliminar y est\u00e1 pendiente del per\u00edodo de apelaci\u00f3n de 30 d\u00edas. Solo aquellos que comentaron sobre la solicitud inicial durante el per\u00edodo de comentarios de 60 d\u00edas son elegibles para presentar una apelaci\u00f3n. Dicha apelaci\u00f3n debe incluir una explicaci\u00f3n de por qu\u00e9 el proyecto no cumple con los criterios de LIHI. Las solicitudes de apelaci\u00f3n se pueden enviar por correo electr\u00f3nico a <a href=\"mailto:comments@lowimpacthydro.org\">comments@lowimpacthydro.org<\/a> con \u201cAshuelot River\/Lower Robertson Hydroelectric Project\u201d en la l\u00ednea de asunto, o por correo dirigido al Low Impact Hydropower Institute, 329 Massachusetts Ave, Suite 6, Lexington, MA 02420. Todas las solicitudes se publicar\u00e1n en el sitio web. El solicitante tendr\u00e1 la oportunidad de responder y cualquier respuesta tambi\u00e9n se publicar\u00e1. <strong>Las solicitudes deben recibirse antes de las 5 p. m., hora del Este, el 26 de octubre de 2019.\u00a0 <\/strong>La solicitud completa y el informe de los revisores est\u00e1n disponibles a continuaci\u00f3n. Si no se reciben solicitudes de apelaci\u00f3n y la decisi\u00f3n se vuelve definitiva, el plazo de Certificaci\u00f3n del Proyecto ser\u00e1 el 29 de junio de 2019 por un per\u00edodo de ocho (8) a\u00f1os, que expirar\u00e1 el 28 de junio de 2027.<\/p>\n<p><strong>11 de junio de 2019:<\/strong>\u00a0El Instituto de Energ\u00eda Hidroel\u00e9ctrica de Bajo Impacto ha recibido una solicitud completa para la Recertificaci\u00f3n de Bajo Impacto de los Proyectos Hidroel\u00e9ctricos Ashuelot River\/Lower Robertson. LIHI est\u00e1 buscando comentarios p\u00fablicos sobre esta solicitud. Espec\u00edficamente, nos interesa saber si usted piensa que el Proyecto cumple con los Criterios de Certificaci\u00f3n de Bajo Impacto de LIHI, seg\u00fan se revisaron en el Manual de la 2.\u00aa Edici\u00f3n. Revise el programa y los criterios en el Manual revisado de LIHI. <a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2016\/03\/2nd-edition-handbook-20160315-rev2.02-7-20-16.pdf\">Manual<\/a><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2014\/08\/2nd-edition-handbook-20160307-FINAL-CLEAN.pdf\">\u00a0<\/a>y luego revise los materiales de solicitud del Proyecto a continuaci\u00f3n. Los comentarios que est\u00e9n directamente relacionados con criterios espec\u00edficos de LIHI (flujos, calidad del agua, paso de peces, etc.) ser\u00e1n de gran ayuda, pero se considerar\u00e1n todos los comentarios. Los comentarios pueden enviarse al Instituto por correo electr\u00f3nico a\u00a0<a href=\"mailto:comments@lowimpacthydro.org\">comments@lowimpacthydro.org<\/a> con \u201cComentarios sobre el Proyecto del R\u00edo Ashuelot\u201d en la l\u00ednea de asunto, o por correo dirigido al Low Impact Hydropower Institute, 329 Massachusetts Avenue, Suite 6, Lexington, MA 02420.\u00a0 <strong>Los comentarios deben recibirse antes de las 5:00 p. m., hora del Este, el 10 de agosto de 2019.<\/strong>\u00a0Se considerar\u00e1n todos los comentarios. Se publicar\u00e1n en el sitio web y el solicitante tendr\u00e1 la oportunidad de responder. Tambi\u00e9n se publicar\u00e1n todas las respuestas.<\/p>\n<p><strong>8 de abril de 2015:<\/strong> El Proyecto Hidroel\u00e9ctrico del R\u00edo Ashuelot ha sido certificado por un segundo per\u00edodo de cinco a\u00f1os de certificaci\u00f3n de bajo impacto, con vigencia a partir del 29 de junio de 2014 y vencimiento el 29 de junio de 2019. Al emitir esta Certificaci\u00f3n, el Director Ejecutivo del Instituto utiliz\u00f3 la autoridad delegada por la Junta Directiva de LIHI y una revisi\u00f3n completa del informe del Revisor de la Solicitud (disponible en la secci\u00f3n Archivos a continuaci\u00f3n) y todos los comentarios p\u00fablicos y materiales adicionales proporcionados por el Solicitante.<\/p>\n<p><strong>4 de septiembre de 2014:<\/strong> El Instituto de Energ\u00eda Hidroel\u00e9ctrica de Bajo Impacto ha recibido una solicitud para un segundo per\u00edodo de certificaci\u00f3n del Proyecto Hidroel\u00e9ctrico del R\u00edo Ashuelot. Los materiales de la solicitud est\u00e1n disponibles en la secci\u00f3n \u201cArchivos\u201d a continuaci\u00f3n.<\/p>\n<p><strong>20 de noviembre de 2009:<\/strong> El Proyecto Hidroel\u00e9ctrico del R\u00edo Ashuelot ha sido certificado como de bajo impacto por un per\u00edodo de cinco a\u00f1os, a partir del 24 de junio de 2009 y hasta el 24 de junio de 2014.<\/p>\n<p><strong>29 de junio de 2009:<\/strong> Ashuelot Hydro, Inc. ha presentado una solicitud de certificaci\u00f3n de los proyectos hidroel\u00e9ctricos Ashuelot y Lower Robertson. El per\u00edodo de comentarios p\u00fablicos para la solicitud permanecer\u00e1 abierto durante 60 d\u00edas, hasta el 30 de agosto de 2009.<\/p>\n<hr \/>\n<h3>Archivos de certificaci\u00f3n<\/h3>\n<h4>Recertificaci\u00f3n 2019<\/h4>\n<ul style=\"color: black;\">\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2025\/01\/Ashuelot-Stage-II-report_2019_09_26.pdf\">Informe de revisi\u00f3n de la recertificaci\u00f3n de Ashuelot 2019<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/2019-Ashuelot-River-Hydro-Application-Complete.pdf\">Solicitud de recertificaci\u00f3n de Ashuelot 2019<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Ashuelot-Response-to-Comments.pdf\">Respuesta de Ashuelot a los comentarios<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Ashuelot-River-Local-Advisory-Committee-Comments.pdf\">Carta de comentarios del Comit\u00e9 asesor local del r\u00edo Ashuelot: recertificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/CRC-Comments-on-Ashuelot-Hydro-LIHI-Application.pdf\">Carta de comentarios de Connecticut River Conservancy: recertificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/NOAA-Comments-Ashuelot-Recertfication.pdf\">Carta de comentarios de la Asociaci\u00f3n Nacional Oce\u00e1nica y Atmosf\u00e9rica: recertificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Owner-response-to-_-quick-questions-on-Ashuelot-application.pdf\">Respuesta del propietario de Ashuelot a las preguntas de la solicitud<\/a><\/li>\n<\/ul>\n<h4>Recertificaci\u00f3n 2014<\/h4>\n<ul style=\"color: black;\">\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/2015-Ashuelot-Recertification-Report.pdf\">Informe de revisi\u00f3n de recertificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Ashuelot-2014-LIHI-Application-for-Recertification.pdf\">Solicitud de recertificaci\u00f3n de Ashuelot 2014<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/BobKingReply_SkulyComment_Re-Certification-Cert.-46-Ashuelot.pdf\">Respuesta del propietario a la carta de comentarios de Skuly<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Comment_BarbaraSkuly_Ashuelot_11032014.pdf\">Carta de comentarios de Barbara Skuly: recertificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/xK-Watershed-Protection-2014.pdf\">Protecci\u00f3n de cuencas hidrogr\u00e1ficas 2014<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/xK-Watershed-Protection-Map.pdf\">Mapa de protecci\u00f3n de cuencas hidrogr\u00e1ficas<\/a><\/li>\n<\/ul>\n<h4>Certificaci\u00f3n 2009<\/h4>\n<ul style=\"color: black;\">\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/LIHI-Reviewer-Report-Ashuelot-NH-10-9-09.pdf\">Informe del revisor de certificaci\u00f3n de Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Ashuelot-River-LIHI-Application-2009.pdf\">Solicitud de Certificaci\u00f3n Ashuelot 2009<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Ashuelot-River-Local-Advisory-Committee-comment-letter_08302009.pdf\">Carta de comentarios del Comit\u00e9 asesor local del r\u00edo Ashuelot: Certificaci\u00f3n Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/Bob-King-response-to-ARLAC_09222009.pdf\">Respuesta del propietario a la carta de comentarios del Comit\u00e9 asesor local del r\u00edo Ashuelot<\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2020\/07\/CRWC-comment-letter_082009.pdf\">Carta de comentarios del Consejo de la Cuenca del R\u00edo Connecticut: Certificaci\u00f3n Ashuelot<\/a><\/li>\n<\/ul>\n<hr \/>\n<h3>Documentos clave<\/h3>\n<ul>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2023\/05\/Ashuelot-FERC-Exemption.pdf\">Ashuelot FERC <span class='tooltipsall tooltip_post_id_5562 classtoolTips113'>Exenci\u00f3n<\/span><\/a><\/li>\n<li><a href=\"https:\/\/lowimpacthydro.org\/wp-content\/uploads\/2023\/05\/Lower-Robertson-FERC-exemption.pdf\">Exenci\u00f3n FERC de Lower Robertson<\/a><\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Project Name Ashuelot Paper &amp; Lower Robertson LIHI Certificate No. 46 LIHI Certificate Term June 29, 2019 &#8211; June 28, 2032 (option to extend to June<span class=\"excerpt-hellip\"> [\u2026]<\/span><\/p>\n","protected":false},"author":3,"featured_media":-1,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-1901","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/pages\/1901","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/comments?post=1901"}],"version-history":[{"count":16,"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/pages\/1901\/revisions"}],"predecessor-version":[{"id":10602,"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/pages\/1901\/revisions\/10602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/lowimpacthydro.org\/es\/wp-json\/wp\/v2\/media?parent=1901"}],"curies":[{"name":"gracias","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}